{"id":12954,"date":"2011-06-20T12:00:58","date_gmt":"2011-06-20T11:00:58","guid":{"rendered":"http:\/\/www.transcend.org\/tms\/?p=12954"},"modified":"2011-06-17T14:16:51","modified_gmt":"2011-06-17T13:16:51","slug":"portuguese-notas-biograficas-dos-paises","status":"publish","type":"post","link":"https:\/\/www.transcend.org\/tms\/2011\/06\/portuguese-notas-biograficas-dos-paises\/","title":{"rendered":"(Portuguese) Notas Biogr\u00e1ficas dos Pa\u00edses (S\u00e1tira)"},"content":{"rendered":"<p>Li uma vez que a Argentina n\u00e3o \u00e9 melhor nem pior que a Espanha; apenas mais jovem. Gostei desta teoria e inventei um truque para descobrir a idade dos pa\u00edses baseando-me no &#8216;sistema c\u00e3o&#8217;. Desde crian\u00e7a nos explicam que para saber a idade de um cachorro basta multiplicar a sua idade biol\u00f3gica por 7.<\/p>\n<p>No caso de pa\u00edses, temos que dividir a sua idade hist\u00f3rica por 14 para saber a sua correspond\u00eancia humana. Confuso? Aqui v\u00e3o alguns exemplos reveladores.<\/p>\n<p>A Argentina nasceu em 1816. Assim sendo, tem 190 anos. Se dividirmos estes anos por 14 veremos que a Argentina tem &#8216;humanamente&#8217; cerca de 13 anos e meio, ou seja, est\u00e1 na pr\u00e9-adolesc\u00eancia. \u00c9 rebelde, n\u00e3o tem mem\u00f3ria, responde sem pensar e tem o rosto coberto de acne.<\/p>\n<p>Quase todos os pa\u00edses da Am\u00e9rica Latina t\u00eam a mesma idade, e como acontece nesses casos, eles formam gangues. A gangue do Mercosul \u00e9 formada por quatro adolescentes &#8211; Argentina, Brasil, Paraguai e Uruguai &#8211; que t\u00eam um conjunto de rock. Ensaiam numa garagem, fazem muito barulho, e jamais gravaram um disco.<\/p>\n<p>A Venezuela, que j\u00e1 tem peitinhos, est\u00e1 querendo unir-se a eles para fazer o coro. Em realidade, como a maioria das mocinhas da sua idade, quer \u00e9 sexo. Neste caso, com o Brasil.<\/p>\n<p>O M\u00e9xico tamb\u00e9m \u00e9 adolescente, mas com ascendente ind\u00edgena. Por isso ri pouco e n\u00e3o fuma simples\u00a0 baseados como o resto dos seus amiguinhos. Mastiga coca e anda com os Estados Unidos, um retardado mental de 17 anos que se diverte atacando meninos famintos e mais fracos, de 6 anos, em outros continentes.<\/p>\n<p>No outro extremo est\u00e1 a China milen\u00e1ria. Se dividirmos os seus 1.200 anos por 14 obteremos uma senhora de 85, conservadora, com cheiro de xixi de gato, que passa o dia comendo arroz porque n\u00e3o tem &#8211; ainda &#8211; dinheiro para comprar uma dentadura posti\u00e7a. A China tem um neto de 8 anos, Taiwan, que lhe faz a vida imposs\u00edvel. Est\u00e1 divorciada faz tempo do Jap\u00e3o, um velho chato que se juntou \u00e0s Filipinas, uma jovem pirada sempre disposta a qualquer aberra\u00e7\u00e3o a troco de grana.<\/p>\n<p>Depois est\u00e3o os pa\u00edses j\u00e1 maiores de idade, que saem com o BMW do pai, como a Austr\u00e1lia e o Canad\u00e1, que cresceram as custas de papai Inglaterra e mam\u00e3e Fran\u00e7a, tiveram uma educa\u00e7\u00e3o restrita e antiquada, e agora d\u00e3o uma de loucos.<\/p>\n<p>A Austr\u00e1lia \u00e9 uma babaca de pouco mais de 18 anos que faz topless e sexo com a \u00c1frica do Sul.<\/p>\n<p>O Canad\u00e1,\u00a0 por outro lado, \u00e9 um mocinho gay, assumido e emancipado, que a qualquer momento pode adotar o bebe da Groenl\u00e2ndia para formar uma dessas fam\u00edlias alternativas da hora, que est\u00e3o na moda.<\/p>\n<p>A Fran\u00e7a \u00e9 uma separada de 36 anos, mais prostituta que uma galinha, mas muito respeitada no \u00e2mbito profissional. Tem um filho de apenas 6 anos, o Monaco, que vai acabar virando gay ou bailarino&#8230; ou ambas as coisas. \u00c9 a amante espor\u00e1dica da Alemanha, um caminhoneiro rico casado com a \u00c1ustria, que sabe que \u00e9 chifruda mas n\u00e3o se importa.<\/p>\n<p>A It\u00e1lia \u00e9 vi\u00fava faz muito tempo. Vive cuidando de S\u00e3o Marino e do Vaticano, dois filhos cat\u00f3licos, gemeos id\u00eanticos. Esteve casada em segundas n\u00fapcias com a Alemanha (por pouco tempo, pariram a Su\u00ed\u00e7a), mas agora n\u00e3o quer saber mais de homens. A It\u00e1lia gostaria de ser uma mulher como a B\u00e9lgica: advogada, executiva independente, que usa cal\u00e7as e fala de pol\u00edtica de igual para igual com os homens (a B\u00e9lgica tamb\u00e9m fantasia de vez em quando que sabe preparar massa. Pura ilus\u00e3o).<\/p>\n<p>A Espanha \u00e9 uma das mulheres mais lindas da Europa (possivelmente a Fran\u00e7a se iguale a ela, mas perde espontaneidade por usar tanto perfume). \u00c9 muito tetuda e quase sempre est\u00e1 b\u00eabada. Geralmente se deixa enganar pela Inglaterra e depois a denuncia. A Espanha tem filhos por todas as partes do mundo (quase todos com 13 anos de idade), os quais moram longe. Gosta muito deles, mas a perturbam quando t\u00eam fome e passam temporadas na sua casa e assaltam sua geladeira.<\/p>\n<p>Outra que tem filhos espalhados pelo mundo todo \u00e9 a Inglaterra. Costumava andar de navio de noite, transava com alguns babacas, e nove meses depois aparecia uma nova comunidade em alguma parte do mundo. Mas em geral se d\u00e3o bem, como uma grande familia, e se ajudam mutuamente.<\/p>\n<p>A Esc\u00f3cia e a Irlanda, irm\u00e3os da Inglaterra que moram no apartamento ao lado e no de cima, passam a vida b\u00eabados e a arrumar confus\u00e3o, e nem sequer sabem jogar futebol. S\u00e3o a vergonha da fam\u00edlia.<\/p>\n<p>A Su\u00e9cia e a Noruega s\u00e3o duas l\u00e9sbicas de quase 40 anos que est\u00e3o bem de corpo, apesar da idade, mas n\u00e3o ligam para ningu\u00e9m. Transam e trabalham, pois s\u00e3o formadas em alguma coisa. \u00c0s vezes fazem trio com a Holanda (quando necessitam maconha ou haxixe); outras vezes cutucam a Finl\u00e2ndia, que \u00e9 um cara meio andr\u00f3gino de 30 anos, que vive s\u00f3 em um apartamento sem mob\u00edlia e passa o tempo falando pelo celular com a Coreia.<\/p>\n<p>A Coreia (a do sul) vive de olho na sua irm\u00e3 esquiz\u00f3ide. S\u00e3o gemeas, mas a do Norte tomou l\u00edquido amni\u00f3tico quando saiu do \u00fatero e ficou est\u00fapida. Passou a inf\u00e2ncia usando pistolas e agora que vive s\u00f3 \u00e9 capaz de qualquer coisa. Os Estados Unidos, o retardadinho de 17 anos, a vigia muito, n\u00e3o por medo, mas porque quer roubar suas pistolas.<\/p>\n<p>Ir\u00e3o e Iraque eram dois primos de 16 anos que roubavam motos e vendiam as pe\u00e7as, at\u00e9 que um dia roubaram uma pe\u00e7a da Harley dos Estados Unidos, o que acabou o neg\u00f3cio para eles. Agora est\u00e3o comendo grama.<\/p>\n<p>O mundo estava indo bem assim, at\u00e9 que um dia a R\u00fassia se juntou (sem casar) com a Perestroika e tiveram uma d\u00fazia e meia de filhos. Todos esquisitos, alguns mongol\u00f3ides, outros esquizofrenicos.<\/p>\n<p>Portugal \u00e9 um cota de 62 anos que n\u00e3o quer saber dos filhos bastardos que teve na \u00c1frica, todos ao redor dos 2 anos de idade. Enquanto perde-se de amores e desejos pela enteada  morena, quente, de 14 aninhos, que do outro lado do Atl\u00e2ntico se insinua  emergente e tesuda ao som do Samba. Proxeneta por tradi\u00e7\u00e3o, sendo um dos mais idosos da Europa acha que os outros t\u00eam obriga\u00e7\u00e3o de sustenta-lo, e  para tal aplica estratagemas e chantagem emocional. Se  necess\u00e1rio, at\u00e9 canta o Fado.<\/p>\n<p>\u00c0s suas custas vivem duas belas filhas solteironas j\u00e1 quarentonas:  uma toda virada para a ecologia, com uns olhos azuis lindos como lagoas;  e a outra, muito rebelde, amea\u00e7a casar-se sempre que a mesada tarda.  Ambas com um temperamento assaz vulc\u00e2nico, prometem ainda dar que falar:  a primeira tem sempre a cama feita para um jovem rica\u00e7o que a visita  amiude de avi\u00e3o; e a segunda, de t\u00e3o bela, d\u00e1-se ao luxo de nem se  depilar da sua floresta laurissilva, recentemente eleita para Patrimonio  Mundial da Humanidade.<\/p>\n<p>Ent\u00e3o eu pergunto: por que continuam a nascer pa\u00edses se os que a\u00ed est\u00e3o n\u00e3o funcionam?<\/p>\n<p>___________________________<\/p>\n<p><em>Hern\u00e1n Casciari nasceu em Mercedes (Buenos Aires), a 16 de Mar\u00e7o de 1971.<\/em><em> Escritor e jornalista Argentino. \u00c9 conhecido por seu trabalho ficcional na Internet, onde tem trabalhado na uni\u00e3o entre literatura e blog, destacado na blognovela. Sua obra mais conhecida na rede, <\/em>&#8216;Weblog de una mujer gorda<em>&#8216;, foi editada em papel, com o t\u00edtulo: <\/em>&#8216;M\u00e1s respeto, que soy tu madre&#8217;.<em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No caso de pa\u00edses, temos que dividir a sua idade hist\u00f3rica por 14 para saber a sua correspond\u00eancia humana. Confuso? Aqui v\u00e3o alguns exemplos reveladores. A Argentina nasceu em 1816. Assim sendo, tem 190 anos. Se dividirmos estes anos por 14 veremos que a Argentina tem &#8216;humanamente&#8217; cerca de 13 anos e meio, ou seja, est\u00e1 na pr\u00e9-adolesc\u00eancia. \u00c9 rebelde, n\u00e3o tem mem\u00f3ria, responde sem pensar e tem o rosto coberto de acne.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-12954","post","type-post","status-publish","format-standard","hentry","category-original-languages"],"_links":{"self":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/posts\/12954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/comments?post=12954"}],"version-history":[{"count":0,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/posts\/12954\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/media?parent=12954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/categories?post=12954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/tags?post=12954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}