{"id":69612,"date":"2016-02-08T12:00:38","date_gmt":"2016-02-08T12:00:38","guid":{"rendered":"https:\/\/www.transcend.org\/tms\/?p=69612"},"modified":"2016-02-08T10:51:15","modified_gmt":"2016-02-08T10:51:15","slug":"portugues-rede-de-tuneis-de-12-mil-anos-que-cruza-toda-europa-intriga-pesquisadores","status":"publish","type":"post","link":"https:\/\/www.transcend.org\/tms\/2016\/02\/portugues-rede-de-tuneis-de-12-mil-anos-que-cruza-toda-europa-intriga-pesquisadores\/","title":{"rendered":"(Portugu\u00eas) Rede de T\u00faneis de 12 mil anos que cruza toda Europa intriga pesquisadores"},"content":{"rendered":"<p><em>Datadas em mais de 12 mil anos, essas passagens subterr\u00e2neas ainda permanecem um mist\u00e9rio. Quem as construiu? Para qu\u00ea? Como foi poss\u00edvel?<\/em><\/p>\n<div id=\"attachment_69613\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/erdstall-tuneis-europa-escocia-turquia.jpg\"  rel=\"attachment wp-att-69613\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69613\" class=\"size-full wp-image-69613\" src=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/erdstall-tuneis-europa-escocia-turquia.jpg\" alt=\"Entrada para o Erdstall em Perg, \u00c1ustria. O t\u00fanel abrange a \u00c1ustria e Alemanha, por\u00e9m segundo Dr. Kusch, h\u00e1 uma liga\u00e7\u00e3o entre t\u00faneis que v\u00e3o desde a Esc\u00f3cia at\u00e9 a Turquia.\" width=\"630\" height=\"354\" srcset=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/erdstall-tuneis-europa-escocia-turquia.jpg 630w, https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/erdstall-tuneis-europa-escocia-turquia-300x169.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><p id=\"caption-attachment-69613\" class=\"wp-caption-text\">Entrada para o Erdstall em Perg, \u00c1ustria. O t\u00fanel abrange a \u00c1ustria e Alemanha, por\u00e9m segundo Dr. Kusch, h\u00e1 uma liga\u00e7\u00e3o entre t\u00faneis que v\u00e3o desde a Esc\u00f3cia at\u00e9 a Turquia.<\/p><\/div>\n<p>Diferente do que a grande maioria pensa, a maior parte do nosso planeta ainda n\u00e3o foi catalogada, e diariamente novas descobertas s\u00e3o feitas, e nem sempre elas s\u00e3o o que pensamos..<\/p>\n<p>Foram encontradas t\u00faneis atrav\u00e9s de toda a Europa, um sistema intermin\u00e1vel de passagens subterr\u00e2neas, que hoje, 12 mil anos depois de sua cria\u00e7\u00e3o, continua de p\u00e9. Apesar de n\u00e3o existirem grandes estudos oficiais a respeito, acredita-se que elas foram constru\u00eddas na Idade da Pedra e que conseguiram atravessar todo o continente europeu, desde a Esc\u00f3cia, passando pela Alemanha e \u00c1ustria, at\u00e9 a Turquia.<\/p>\n<p><a href=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tunel-europa-turquia-escocia.jpg\"  rel=\"attachment wp-att-69614\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-69614 size-full\" src=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tunel-europa-turquia-escocia.jpg\" alt=\"Em todo o continente, contam-se milhares e milhares de t\u00faneis, a grande maioria muito estreitos, de somente 70 cm de di\u00e2metro, o suficiente para uma pessoa.\" width=\"470\" height=\"504\" srcset=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tunel-europa-turquia-escocia.jpg 470w, https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tunel-europa-turquia-escocia-280x300.jpg 280w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/a><\/p>\n<p>Em todo o continente, contam-se milhares e milhares de t\u00faneis, a grande maioria muito estreitos, de somente 70 cm de di\u00e2metro, o suficiente para uma pessoa.<\/p>\n<p>Entre as v\u00e1rias passagens, existem alguns setores maiores ou menores, nos quais h\u00e1 assentos e salas de armazenamento.<\/p>\n<p>Um dos primeiros exploradores desse sistema de t\u00faneis foi o sacerdote <em>Lambert Karner<\/em> (1841-1909), que se arrastou pelos 400 buracos, com a ajuda de uma vela, e que descreveu \u201cestranhas passagens com correntes de ar\u201d, segundo a revista<strong> Der <\/strong><strong><a target=\"_blank\" href=\"http:\/\/www.spiegel.de\/international\/zeitgeist\/hideouts-or-sacred-spaces-experts-baffled-by-mysterious-underground-chambers-a-775348.html\" >Spiegel<\/a><\/strong>.<\/p>\n<p>A falta de qualquer ind\u00edcio sobre o porqu\u00ea de sua exist\u00eancia fez com que muitos especialistas se referissem a essas constru\u00e7\u00f5es como o \u00faltimo grande mist\u00e9rio da Europa. Enquanto isso, a tradi\u00e7\u00e3o popular acredita que eles foram constru\u00eddos e escavados por elfos, ou gnomos, figuras t\u00edpicas do folclore celta.<\/p>\n<div id=\"attachment_69615\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/mapa-tuneis-escocia-turquia.png\"  rel=\"attachment wp-att-69615\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-69615\" class=\"wp-image-69615\" src=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/mapa-tuneis-escocia-turquia.png\" alt=\"Ainda n\u00e3o foi poss\u00edvel catalogar todas as localiza\u00e7\u00f5es exatas das gigantescas passagens.\" width=\"700\" height=\"308\" srcset=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/mapa-tuneis-escocia-turquia.png 847w, https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/mapa-tuneis-escocia-turquia-300x132.png 300w, https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/mapa-tuneis-escocia-turquia-768x338.png 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-69615\" class=\"wp-caption-text\">Ainda n\u00e3o foi poss\u00edvel catalogar todas as localiza\u00e7\u00f5es exatas das gigantescas passagens.<\/p><\/div>\n<p>Alguns especialistas afirmam que a rede de t\u00faneis funcionou como prote\u00e7\u00e3o para as pessoas contra predadores; outras acreditam que foi utilizada como caminho, para viagens com seguran\u00e7a, independentemente das guerras ou fatores clim\u00e1ticos.<\/p>\n<p>Curiosamente, algumas das entradas come\u00e7am na cozinha de alguma casa at\u00e9 a igreja, cemit\u00e9rio ou at\u00e9 mesmo leva \u00e0 floresta. A melhor resposta encontrada at\u00e9 agora foi de que eram ref\u00fagios em caso de ataques surpresa, por\u00e9m nenhum material org\u00e2nico ou outro objeto, como comida, foi encontrado.<\/p>\n<p><a href=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tuneis-europa-escocia-turquia.jpg\"  rel=\"attachment wp-att-69616\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-69616\" src=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tuneis-europa-escocia-turquia.jpg\" alt=\"tuneis-europa-escocia turquia\" width=\"594\" height=\"281\" srcset=\"https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tuneis-europa-escocia-turquia.jpg 594w, https:\/\/www.transcend.org\/tms\/wp-content\/uploads\/2016\/02\/tuneis-europa-escocia-turquia-300x142.jpg 300w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a><\/p>\n<p>O arque\u00f3logo alem\u00e3o Dr. Kusch, escreveu em seu livro <em>\u201cSegredos da Porta do Mundo Subterr\u00e2neo para o Mundo Antigo\u201d<\/em>, que apenas em Bavaria, na Alemanha, foram encontrados 700 metros de conex\u00f5es subterr\u00e2neas, e que elas se espalham desde o norte da Esc\u00f3cia at\u00e9 o Mediterr\u00e2neo.<\/p>\n<p>Ainda permanece um mist\u00e9rio como uma complexa e gigantesca rede de t\u00faneis foi criada h\u00e1 tanto tempo atr\u00e1s.<\/p>\n<p><a target=\"_blank\" href=\"http:\/\/tonocosmos.com.br\/rede-de-tuneis-de-12-mil-anos-que-cruza-toda-europa\" >Go to Original \u2013 tonocosmos.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datadas em mais de 12 mil anos, essas passagens subterr\u00e2neas ainda permanecem um mist\u00e9rio. Quem as construiu? Para qu\u00ea? Como foi poss\u00edvel?<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-69612","post","type-post","status-publish","format-standard","hentry","category-original-languages"],"_links":{"self":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/posts\/69612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/comments?post=69612"}],"version-history":[{"count":0,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/posts\/69612\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/media?parent=69612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/categories?post=69612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.transcend.org\/tms\/wp-json\/wp\/v2\/tags?post=69612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}